{"id":266,"count":1,"description":"","link":"https:\/\/blog.rehairsystem.com\/pl\/tag\/ile-mieszkow-wlosowych-na-ludzkiej-glowie\/","name":"How Many Hair Follicles on A Human Head","slug":"how-many-hair-follicles-on-a-human-head","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blog.rehairsystem.com\/pl\/wp-json\/wp\/v2\/tags\/266"}],"collection":[{"href":"https:\/\/blog.rehairsystem.com\/pl\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.rehairsystem.com\/pl\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.rehairsystem.com\/pl\/wp-json\/wp\/v2\/posts?tags=266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}